{"id":841,"date":"2025-04-30T17:37:43","date_gmt":"2025-04-30T15:37:43","guid":{"rendered":"https:\/\/analemma-water.nl\/?post_type=legal&#038;p=841"},"modified":"2026-01-30T11:21:48","modified_gmt":"2026-01-30T10:21:48","slug":"datenschutzerklaerung","status":"publish","type":"legal","link":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Water and Light B.V. hat seinen Sitz in Bisschopsweg 2, 3732 HW, De Bilt, Niederlande, EU, und ist in den Niederlanden unter der Handelskammer-Registrierungsnummer 64419312 und der Umsatzsteuer-Identifikationsnummer NL855658605B01 registriert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allgemeines<br>Der sorgf\u00e4ltige Umgang mit personenbezogenen Daten ist f\u00fcr uns von gro\u00dfer Bedeutung. Personenbezogene Daten werden daher von uns sorgf\u00e4ltig verarbeitet und gesichert. Bei der Verarbeitung halten wir uns an die Vorgaben der Allgemeinen Datenschutzverordnung. In dieser Erkl\u00e4rung erl\u00e4utern wir, welche personenbezogenen Daten wir zu welchem Zweck erheben und verwenden. Wir empfehlen Ihnen, diese Erkl\u00e4rung sorgf\u00e4ltig zu lesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sicherheit<br>Wir unternehmen alle Anstrengungen, um die Website gegen Missbrauch und unbefugten Zugriff auf personenbezogene Daten zu sch\u00fctzen. Wir tun dies zum Beispiel durch SSL-gesicherte Verbindungen. Es liegt in Ihrer Verantwortung, die Ger\u00e4te, mit denen Sie unsere Website besuchen und nutzen, zu sichern, z.B. durch einen Virenscanner.<br>Personenbezogene Daten<br>Wenn Sie unsere Website nutzen, hinterlassen Sie uns bestimmte Daten. Dabei kann es sich um personenbezogene Daten handeln: Daten, die direkt oder indirekt auf Sie zur\u00fcckgef\u00fchrt werden k\u00f6nnen. Wir speichern und verwenden nur die personenbezogenen Daten, die Sie uns direkt zur Verf\u00fcgung stellen oder von denen bei der \u00dcbermittlung klar ist, dass sie uns zur Bearbeitung zur Verf\u00fcgung gestellt werden.<br>Wir verwenden die erhaltenen personenbezogenen Daten nur f\u00fcr die Zwecke, f\u00fcr die wir die Daten von Ihnen erhalten haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Newsletter<br>Wenn Sie sich f\u00fcr unseren Newsletter anmelden und wir Sie um Daten bitten, verwenden wir diese Daten nur, um Ihnen unseren Newsletter per E-Mail zuzusenden. Sie k\u00f6nnen den Newsletter jederzeit wieder abbestellen, indem Sie den Abmeldelink im Newsletter benutzen. Sobald Sie den Newsletter abbestellen, werden wir Ihre personenbezogenen Daten, die mit dem Newsletter in Verbindung stehen oder standen, unverz\u00fcglich l\u00f6schen. Die Grundlage, auf der wir personenbezogene Daten verarbeiten, ist, dass wir Ihren Wunsch nach dem Erhalt des Newsletters erf\u00fcllen k\u00f6nnen.<br>Dar\u00fcber hinaus verarbeiten wir Ihre Daten zu statistischen Zwecken. Dies erm\u00f6glicht uns, allgemeine Erkenntnisse zu gewinnen, z. B. demografische Erkenntnisse.<br>Wir erheben Ihre personenbezogenen Daten auch, um ein Profil zu erstellen. Dies geschieht z. B. auf der Grundlage, welche Links Sie im Newsletter anklicken, auf welchem Ger\u00e4t Sie den Newsletter am liebsten lesen oder wann Sie den Newsletter lesen.<br>Die Grundlage f\u00fcr die Erstellung eines Profils ist in diesem Fall ein berechtigtes Interesse: Wir k\u00f6nnen Ihnen bessere Inhalte anbieten.<br>Wir verarbeiten nicht mehr Daten als f\u00fcr diesen Zweck erforderlich und Ihre Interessen, Grundrechte und Freiheiten werden nicht beeintr\u00e4chtigt. Wenn Sie den Newsletter abbestellen, wird auch Ihr Profil, sofern vorhanden, gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kontakt-Formular<br>Wenn Sie eine Frage stellen oder mit uns Kontakt aufnehmen m\u00f6chten, verwenden Sie bitte das Kontaktformular auf unserer Website. Die Daten, die Sie uns \u00fcber das Kontaktformular zur Verf\u00fcgung stellen, verwenden wir nur, um Ihre Frage oder Ihren Kommentar zu beantworten. Nach der Beantwortung werden wir Ihre personenbezogenen Daten l\u00f6schen.<br>Die Grundlage, auf der wir personenbezogene Daten verarbeiten, ist: die Erf\u00fcllung Ihrer Informationsanfrage oder die Beantwortung Ihres Kommentars.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stellenbewerbung<br>Wenn Sie im Zusammenhang mit einer Bewerbung Daten auf unserer Website hinterlassen, werden wir diese Daten nur zum Zweck des Bewerbungsverfahrens f\u00fcr die Stelle, auf die Sie sich beworben haben, verwenden. Wenn die Stelle, auf die Sie sich beworben haben, besetzt oder zur\u00fcckgezogen wird, werden wir die von Ihnen hinterlassenen Daten wie Lebenslauf und Motivationsschreiben vernichten, es sei denn, wir haben Ihre Erlaubnis eingeholt, die Daten f\u00fcr eventuelle k\u00fcnftige Stellenausschreibungen l\u00e4nger aufzubewahren.<br>Die Grundlage, auf der wir personenbezogene Daten verarbeiten, ist: die (vorvertragliche) Erf\u00fcllung eines (Arbeits-)Vertrags.<br>Bitte beachten Sie, dass ein Passfoto, Geburtsort oder -land und Mitgliedschaften in Gewerkschaften, sexuelle Orientierung, Gesundheitszustand besondere personenbezogene Daten sind. Sie m\u00fcssen diese weder in Ihrem Lebenslauf oder Anschreiben erw\u00e4hnen, noch sind sie f\u00fcr die Beurteilung Ihrer Bewerbung von Bedeutung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beauftragung von Drittparteien<br>Wir k\u00f6nnen Dritte damit beauftragen, personenbezogene Daten in unserem Namen zu verarbeiten. Diese Dritten werden in solchen F\u00e4llen als \u201eAuftragsverarbeiter\u201c bezeichnet. Diese Auftragsverarbeiter handeln stets unter unserer Verantwortung und d\u00fcrfen die personenbezogenen Daten nicht f\u00fcr ihre eigenen Zwecke verwenden. Wir haben mit diesen Dritten Verarbeitungsvertr\u00e4ge abgeschlossen.<br>Dazu geh\u00f6ren unser Hosting-Anbieter und Anbieter von Online-Tools. Diese Online-Tools erm\u00f6glichen es uns zum Beispiel, den Newsletter zu versenden, Ihre Fragen oder Kommentare zu bearbeiten oder Ihre Bewerbung zu bearbeiten.<br>Wir k\u00f6nnen Software von Drittanbietern verwenden, um Bewerbungen zu bearbeiten.<br>Personenbezogene Daten k\u00f6nnen au\u00dferhalb der Europ\u00e4ischen Union oder der Europ\u00e4ischen Union verarbeitet werden. Dies betrifft in der Regel die Vereinigten Staaten. Wir stellen sicher, dass die Dritten, die Ihre personenbezogenen Daten verarbeiten, nach dem Privacy Shield zertifiziert sind oder mit den Muster\u00fcbertragungsvertr\u00e4gen der EU arbeiten.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookies<br>Auf unserer Website werden Cookies eingesetzt. Wie wir mit Cookies umgehen, haben wir in einer separaten Cookie-Erkl\u00e4rung festgehalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Websites oder Dienste von Drittanbietern<br>Diese Erkl\u00e4rung gilt nicht f\u00fcr Websites oder Dienste Dritter, die mit unserer Website durch Links oder auf andere Weise verbunden sind. Wir k\u00f6nnen nicht garantieren, dass diese Dritten Ihre pers\u00f6nlichen Daten auf zuverl\u00e4ssige oder sichere Weise behandeln. Wir empfehlen Ihnen, die Datenschutzerkl\u00e4rungen oder andere (allgemeine) Gesch\u00e4ftsbedingungen dieser Websites oder Dienste zu lesen, bevor Sie die Websites oder Dienste dieser Dritten nutzen.<br>Fragen, Recht auf Einsichtnahme, Berichtigung und L\u00f6schung<br>Bei Fragen zu unserer Datenschutzpolitik oder bei Fragen zur Einsichtnahme und \u00c4nderung (oder L\u00f6schung) Ihrer personenbezogenen Daten k\u00f6nnen Sie sich jederzeit an uns wenden. Um Missbrauch vorzubeugen, k\u00f6nnen wir Sie bitten, sich dabei entsprechend auszuweisen.<br>Sie haben nach dem AVG folgende Rechte:<br>\uf0a7 Das Recht auf Einsichtnahme und Berichtigung oder L\u00f6schung personenbezogener Daten oder Einschr\u00e4nkung der Verarbeitung sowie das Recht auf Widerspruch gegen die (weitere) Verarbeitung.<br>\uf0a7 Das Recht, Ihre Daten zu entnehmen und\/oder zu \u00fcbertragen.<br>\uf0a7 Beruht die Verarbeitung personenbezogener Daten auf einer Einwilligung, haben Sie das Recht, diese Einwilligung jederzeit zu widerrufen.<br>\uf0a7 Sie haben das Recht, bei der Datenschutzbeh\u00f6rde eine Beschwerde \u00fcber die Verarbeitung Ihrer personenbezogenen Daten durch uns einzureichen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c4nderungen<br>Wir behalten uns das Recht vor, diese Erkl\u00e4rung zum Datenschutz jederzeit zu \u00e4ndern. Bitte konsultieren Sie diesen Text daher regelm\u00e4\u00dfig, um sicherzustellen, dass Sie die neueste Version zur Kenntnis genommen haben.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"template":"","class_list":["post-841","legal","type-legal","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Analemma Water<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Analemma Water\" \/>\n<meta property=\"og:description\" content=\"Water and Light B.V. hat seinen Sitz in Bisschopsweg 2, 3732 HW, De Bilt, Niederlande, EU, und ist in den Niederlanden unter der Handelskammer-Registrierungsnummer 64419312 und der Umsatzsteuer-Identifikationsnummer NL855658605B01 registriert. AllgemeinesDer sorgf\u00e4ltige Umgang mit personenbezogenen Daten ist f\u00fcr uns von gro\u00dfer Bedeutung. Personenbezogene Daten werden daher von uns sorgf\u00e4ltig verarbeitet und gesichert. Bei der Verarbeitung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Analemma Water\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T10:21:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/analemma-water.nl\/wp-content\/uploads\/af-logo-analemma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/legal\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/legal\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - Analemma Water\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#website\"},\"datePublished\":\"2025-04-30T15:37:43+00:00\",\"dateModified\":\"2026-01-30T10:21:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/legal\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/analemma-water.nl\\\/de\\\/legal\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/legal\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/\",\"name\":\"Analemma Water\",\"description\":\"INCREDIBLE POWER OF WATER UNLEASHED\",\"publisher\":{\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#organization\"},\"alternateName\":\"Analemma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#organization\",\"name\":\"Analemma Water\",\"alternateName\":\"Water and Light B.V.\",\"url\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/analemma-water.nl\\\/wp-content\\\/uploads\\\/AW_696x696px.png\",\"contentUrl\":\"https:\\\/\\\/analemma-water.nl\\\/wp-content\\\/uploads\\\/AW_696x696px.png\",\"width\":696,\"height\":696,\"caption\":\"Analemma Water\"},\"image\":{\"@id\":\"https:\\\/\\\/analemma-water.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Analemma Water","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Analemma Water","og_description":"Water and Light B.V. hat seinen Sitz in Bisschopsweg 2, 3732 HW, De Bilt, Niederlande, EU, und ist in den Niederlanden unter der Handelskammer-Registrierungsnummer 64419312 und der Umsatzsteuer-Identifikationsnummer NL855658605B01 registriert. AllgemeinesDer sorgf\u00e4ltige Umgang mit personenbezogenen Daten ist f\u00fcr uns von gro\u00dfer Bedeutung. Personenbezogene Daten werden daher von uns sorgf\u00e4ltig verarbeitet und gesichert. Bei der Verarbeitung [&hellip;]","og_url":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/","og_site_name":"Analemma Water","article_modified_time":"2026-01-30T10:21:48+00:00","og_image":[{"width":400,"height":200,"url":"https:\/\/analemma-water.nl\/wp-content\/uploads\/af-logo-analemma.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/","url":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Analemma Water","isPartOf":{"@id":"https:\/\/analemma-water.nl\/de\/#website"},"datePublished":"2025-04-30T15:37:43+00:00","dateModified":"2026-01-30T10:21:48+00:00","breadcrumb":{"@id":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/analemma-water.nl\/de\/legal\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analemma-water.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/analemma-water.nl\/de\/#website","url":"https:\/\/analemma-water.nl\/de\/","name":"Analemma Water","description":"INCREDIBLE POWER OF WATER UNLEASHED","publisher":{"@id":"https:\/\/analemma-water.nl\/de\/#organization"},"alternateName":"Analemma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analemma-water.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/analemma-water.nl\/de\/#organization","name":"Analemma Water","alternateName":"Water and Light B.V.","url":"https:\/\/analemma-water.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/analemma-water.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/analemma-water.nl\/wp-content\/uploads\/AW_696x696px.png","contentUrl":"https:\/\/analemma-water.nl\/wp-content\/uploads\/AW_696x696px.png","width":696,"height":696,"caption":"Analemma Water"},"image":{"@id":"https:\/\/analemma-water.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/analemma-water.nl\/de\/wp-json\/wp\/v2\/legal\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analemma-water.nl\/de\/wp-json\/wp\/v2\/legal"}],"about":[{"href":"https:\/\/analemma-water.nl\/de\/wp-json\/wp\/v2\/types\/legal"}],"wp:attachment":[{"href":"https:\/\/analemma-water.nl\/de\/wp-json\/wp\/v2\/media?parent=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}